{"id":447,"date":"2013-06-26T19:28:36","date_gmt":"2013-06-26T19:28:36","guid":{"rendered":"http:\/\/www.wensmedia.com\/ens-on-sales\/?p=447"},"modified":"2013-06-26T19:28:36","modified_gmt":"2013-06-26T19:28:36","slug":"the-metrics-of-selling","status":"publish","type":"post","link":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/","title":{"rendered":"The Metrics of Selling"},"content":{"rendered":"<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"100%\">\n<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"15\">\n<tbody>\n<tr>\n<td align=\"left\">\n<div align=\"center\">\n<div align=\"center\">\n<p>The Metrics of Selling<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"100%\">\n<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"15\" bgcolor=\"#ffffff\">\n<tbody>\n<tr>\n<td align=\"left\">\n<div>\n<div>\n<div>\n<p>According to the National Sales Executive Association, 80% of all new business is won after the fifth contact.<\/p>\n<p>Our own research of SoundADvice member activity reveals similar results; the average size of a first order is four times greater after a prospect has received five to seven SoundADvice contacts.<\/p>\n<p>What are the key take-aways from this research?<\/p>\n<p>1.)\u00a0 Advertisers buy from account executives they trust, and building trust takes time.<\/p>\n<p>2.)\u00a0 Don&#8217;t expect an order on a first call, and don&#8217;t give up too early.<\/p>\n<p>3.)\u00a0 A call that does not yield an order should not be considered unsuccessful; instead consider it to be an advancement towards success.<\/p>\n<p>4.)\u00a0 Have a strategic plan in place to generate a minimum of 5 to 7 valid business contacts with your prospect as you advance towards that order. A &#8220;valid business contact&#8221; is any contact which benefits your prospect and enhances your brand as a helpful marketing professional.<\/p>\n<p>One final point: Never think of getting an order as the end of your selling process. It&#8217;s actually just the beginning towards the next bigger order if you plan another 5 valid business contacts immediately following that first order.<\/p>\n<p>P.S. Our SoundADvice system creates valid business contacts for you every week.<\/p>\n<p>Contact <span style=\"color: #000000;\">Peter@wensmedia.com<\/span>\u00a0to learn how a SoundADvice membership can increase your local direct sales.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"15\" bgcolor=\"#ffffff\">\n<tbody>\n<tr>\n<td align=\"left\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>The Metrics of Selling According to the National Sales Executive Association, 80% of all new business is won after the fifth contact. Our own research of SoundADvice member activity reveals similar results; the average size of a first order is four times greater after a prospect has received five to seven SoundADvice contacts. What are [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-447","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Metrics of Selling - ENS on Sales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Metrics of Selling - ENS on Sales\" \/>\n<meta property=\"og:description\" content=\"The Metrics of Selling According to the National Sales Executive Association, 80% of all new business is won after the fifth contact. Our own research of SoundADvice member activity reveals similar results; the average size of a first order is four times greater after a prospect has received five to seven SoundADvice contacts. What are [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/\" \/>\n<meta property=\"og:site_name\" content=\"ENS on Sales\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-26T19:28:36+00:00\" \/>\n<meta name=\"author\" content=\"ensonsales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ensonsales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/\"},\"author\":{\"name\":\"ensonsales\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#\\\/schema\\\/person\\\/74b922927ea9a0ddb2c3c3211c970180\"},\"headline\":\"The Metrics of Selling\",\"datePublished\":\"2013-06-26T19:28:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#organization\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/\",\"url\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/\",\"name\":\"The Metrics of Selling - ENS on Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#website\"},\"datePublished\":\"2013-06-26T19:28:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/uncategorized\\\/the-metrics-of-selling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Metrics of Selling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#website\",\"url\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/\",\"name\":\"ENS on Sales\",\"description\":\"All About Radio Sales\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#organization\",\"name\":\"ENS on Sales\",\"url\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Ens-Media-logo-square.png\",\"contentUrl\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Ens-Media-logo-square.png\",\"width\":1000,\"height\":1000,\"caption\":\"ENS on Sales\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/#\\\/schema\\\/person\\\/74b922927ea9a0ddb2c3c3211c970180\",\"name\":\"ensonsales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a9ee263c8e96d87977f526af077b335a0b737a673757f50d6a6d516289421de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a9ee263c8e96d87977f526af077b335a0b737a673757f50d6a6d516289421de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a9ee263c8e96d87977f526af077b335a0b737a673757f50d6a6d516289421de?s=96&d=mm&r=g\",\"caption\":\"ensonsales\"},\"sameAs\":[\"https:\\\/\\\/www.ensmediausa.com\\\/\"],\"url\":\"https:\\\/\\\/www.ensmediausa.com\\\/ens-on-sales\\\/author\\\/ensonsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Metrics of Selling - ENS on Sales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/","og_locale":"en_US","og_type":"article","og_title":"The Metrics of Selling - ENS on Sales","og_description":"The Metrics of Selling According to the National Sales Executive Association, 80% of all new business is won after the fifth contact. Our own research of SoundADvice member activity reveals similar results; the average size of a first order is four times greater after a prospect has received five to seven SoundADvice contacts. What are [&hellip;]","og_url":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/","og_site_name":"ENS on Sales","article_published_time":"2013-06-26T19:28:36+00:00","author":"ensonsales","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ensonsales","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/#article","isPartOf":{"@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/"},"author":{"name":"ensonsales","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#\/schema\/person\/74b922927ea9a0ddb2c3c3211c970180"},"headline":"The Metrics of Selling","datePublished":"2013-06-26T19:28:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#organization"},"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/","url":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/","name":"The Metrics of Selling - ENS on Sales","isPartOf":{"@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#website"},"datePublished":"2013-06-26T19:28:36+00:00","breadcrumb":{"@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/uncategorized\/the-metrics-of-selling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensmediausa.com\/ens-on-sales\/"},{"@type":"ListItem","position":2,"name":"The Metrics of Selling"}]},{"@type":"WebSite","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#website","url":"https:\/\/www.ensmediausa.com\/ens-on-sales\/","name":"ENS on Sales","description":"All About Radio Sales","publisher":{"@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensmediausa.com\/ens-on-sales\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#organization","name":"ENS on Sales","url":"https:\/\/www.ensmediausa.com\/ens-on-sales\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#\/schema\/logo\/image\/","url":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-content\/uploads\/2026\/08\/Ens-Media-logo-square.png","contentUrl":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-content\/uploads\/2026\/08\/Ens-Media-logo-square.png","width":1000,"height":1000,"caption":"ENS on Sales"},"image":{"@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ensmediausa.com\/ens-on-sales\/#\/schema\/person\/74b922927ea9a0ddb2c3c3211c970180","name":"ensonsales","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6a9ee263c8e96d87977f526af077b335a0b737a673757f50d6a6d516289421de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a9ee263c8e96d87977f526af077b335a0b737a673757f50d6a6d516289421de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a9ee263c8e96d87977f526af077b335a0b737a673757f50d6a6d516289421de?s=96&d=mm&r=g","caption":"ensonsales"},"sameAs":["https:\/\/www.ensmediausa.com\/"],"url":"https:\/\/www.ensmediausa.com\/ens-on-sales\/author\/ensonsales\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/posts\/447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/comments?post=447"}],"version-history":[{"count":3,"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/posts\/447\/revisions"}],"predecessor-version":[{"id":450,"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/posts\/447\/revisions\/450"}],"wp:attachment":[{"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/media?parent=447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/categories?post=447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensmediausa.com\/ens-on-sales\/wp-json\/wp\/v2\/tags?post=447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}